{"id":3578,"date":"2020-12-18T16:40:40","date_gmt":"2020-12-18T16:40:40","guid":{"rendered":"http:\/\/www.temopese.it\/?p=3578"},"modified":"2021-07-23T07:54:25","modified_gmt":"2021-07-23T07:54:25","slug":"terminale-numerico-con-stampante","status":"publish","type":"post","link":"https:\/\/www.temopese.it\/fr\/terminale-numerico-con-stampante\/","title":{"rendered":"Terminal num\u00e9rique avec imprimante"},"content":{"rendered":"<p>Notre terminal num\u00e9rique avec imprimante \u00e0 rouleau thermique int\u00e9gr\u00e9e peut \u00eatre connect\u00e9 \u00e0 toutes les plates-formes de pesage \u00e9lectroniques jusqu&#039;\u00e0 8 capteurs de pesage de 350 \u03a9, analogiques et num\u00e9riques.<br \/>\nL&#039;indicateur est \u00e9quip\u00e9 de 2 affichages lumineux pour l&#039;indication du poids et de la tare.<br \/>\nPossibilit\u00e9 d&#039;imprimer via l&#039;imprimante thermique int\u00e9gr\u00e9e, ou directement depuis un ordinateur gr\u00e2ce \u00e0 l&#039;adoption de notre logiciel de gestion.<\/p>\n<h4>Description technique:<\/h4>\n<p>Le terminal est \u00e9quip\u00e9 d&#039;un certificat de test pour une utilisation en tant que module de syst\u00e8me de pesage en combinaison avec d&#039;autres composants approuv\u00e9s selon les guides Welmec. Il est \u00e9galement \u00e9quip\u00e9 d&#039;un certificat d&#039;homologation de type CE conform\u00e9ment aux exigences de la norme EN-45501<\/p>\n<p><strong>Principales caract\u00e9ristiques techniques:<\/strong><br \/>\n\u2022 Conteneur ABS en version table<br \/>\n\u2022 Affichage \u00e0 7 segments, 7 chiffres rouges de 21 mm pour l&#039;affichage du poids<br \/>\n\u2022 Affichage \u00e0 7 segments, 7 chiffres rouges de 13 mm pour l&#039;affichage de la tare<br \/>\n\u2022 N. 8 indicateurs LED<br \/>\n\u2022 Imprimante thermique int\u00e9gr\u00e9e<br \/>\n\u2022 Sorties s\u00e9rie N.4 RS 232\/422\/485<br \/>\n\u2022 Convertisseur A \/ N sigma-delta 24 bits<br \/>\n\u2022 Calibrage et configuration configurables au clavier<br \/>\n\u2022 Version multi-champ \/ multi-division maximale de 10 000e<br \/>\n\u2022 Alimentation: 7,5 Vdc via un adaptateur de 100 \u00e0 240 Vac 47-63 Hz.<br \/>\n\u2022 Batterie tampon interne<br \/>\n\u2022 Gestion des E \/ S 4 IN \/ 4 OUT<br \/>\n\u2022 Entr\u00e9e clavier PC<br \/>\n\u2022 Temp\u00e9rature de fonctionnement de \u201310 \u00b0 C \u00e0 + 40 \u00b0 C<br \/>\n\u2022 Degr\u00e9 de protection IP 54<\/p>\n<h4>Fonctions du logiciel:<\/h4>\n<p><strong>Les principales fonctions du logiciel sont:<\/strong><br \/>\nRemise \u00e0 z\u00e9ro, acquisition, affichage et bloc de tare, stockage de 10 tares, affichage de la division 1\/10, fer de pes\u00e9e, compteur de pi\u00e8ces, configuration du canal s\u00e9rie, r\u00e9glage du code produit, impression simple, impression des totaux et totaux par code, gestion des points de consigne , horloge.<\/p>\n<p><a href=\"http:\/\/www.temopese.it\/wp-content\/uploads\/N-ST.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3579 size-medium\" src=\"http:\/\/www.temopese.it\/wp-content\/uploads\/N-ST-300x129.jpg\" alt=\"\" width=\"300\" height=\"129\" srcset=\"https:\/\/www.temopese.it\/wp-content\/uploads\/N-ST-300x129.jpg 300w, https:\/\/www.temopese.it\/wp-content\/uploads\/N-ST.jpg 424w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Notre terminal num\u00e9rique avec imprimante \u00e0 rouleau thermique int\u00e9gr\u00e9e peut \u00eatre connect\u00e9 \u00e0 toutes les plates-formes de pesage \u00e9lectroniques jusqu&#039;\u00e0<\/p>","protected":false},"author":13,"featured_media":3579,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[231],"tags":[],"class_list":["post-3578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-terminali-elettronici"],"_links":{"self":[{"href":"https:\/\/www.temopese.it\/fr\/wp-json\/wp\/v2\/posts\/3578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.temopese.it\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.temopese.it\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.temopese.it\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.temopese.it\/fr\/wp-json\/wp\/v2\/comments?post=3578"}],"version-history":[{"count":0,"href":"https:\/\/www.temopese.it\/fr\/wp-json\/wp\/v2\/posts\/3578\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.temopese.it\/fr\/wp-json\/wp\/v2\/media\/3579"}],"wp:attachment":[{"href":"https:\/\/www.temopese.it\/fr\/wp-json\/wp\/v2\/media?parent=3578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.temopese.it\/fr\/wp-json\/wp\/v2\/categories?post=3578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.temopese.it\/fr\/wp-json\/wp\/v2\/tags?post=3578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}